{"id":1605,"date":"2023-12-01T21:23:00","date_gmt":"2023-12-01T20:23:00","guid":{"rendered":"https:\/\/jardineriaoscarh.com\/?p=1605"},"modified":"2024-08-20T11:49:01","modified_gmt":"2024-08-20T11:49:01","slug":"en-que-consisteix-la-feina-del-disseny-de-jardins","status":"publish","type":"post","link":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/","title":{"rendered":"En qu\u00e8 consisteix la feina del disseny de jardins"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En primer lloc, hem de saber que el paisatgisme \u00e9s una activitat professional encaminada a millorar les caracter\u00edstiques f\u00edsiques, materials i espirituals dels espais rurals o urbans, amb l&#8217;objectiu d&#8217;expressar valors est\u00e8tics i culturals. Aquest \u00e0mbit de treball inclou plantar arbres, donar forma a elements naturals i crear estructures abstractes a partir d&#8217;una varietat de materials. D&#8217;altra banda, els arquitectes paisatgistes s\u00f3n persones que es especialitzen en la planificaci\u00f3 i el disseny de jardins, tant rurals com urbans, basant-se en les caracter\u00edstiques naturals, aix\u00ed com en els valors culturals i hist\u00f2rics d&#8217;un lloc. Per aconseguir-ho, es fonamenta en un conjunt de principis est\u00e8tics, funcionals i cient\u00edfics, aix\u00ed com en l&#8217;\u00fas d&#8217;una \u00e0mplia gamma de tecnologies i materials naturals i sint\u00e8tics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per tant, entre les principals funcions del paisatgisme, que detallarem m\u00e9s endavant, trobem l&#8217;organitzaci\u00f3 i execuci\u00f3 de projectes dedicats al disseny de jardins i espais verds. Ara, un paisatgista pot especialitzar-se en diferents camps. En general, el disseny de jardins pot funcionar en diferents projectes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Passos necessaris per al disseny de jardins<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abans de crear un jard\u00ed, \u00e9s important tenir un bon disseny en el qual es tinguin en compte tots els factors propis d&#8217;aquest espai, el tipus de jard\u00ed que es vol fer, l&#8217;\u00fas que se li donar\u00e0 i el que vol el client.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En segon lloc, un cop veiem les condicions que tenim, avaluarem quin tipus de jard\u00ed tenim. A l&#8217;hora de comen\u00e7ar amb el disseny de jardins, no tractarem un petit jard\u00ed per a una vivenda unifamiliar com un jard\u00ed urb\u00e0. Cada espai dep\u00e8n de la seva mida i l&#8217;\u00fas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segons les persones que utilitzin aquest parc, el disseny estar\u00e0 pensat d&#8217;una manera o altra (espais oberts, zones arbrades, jocs infantils&#8230;). Finalment, cal saber qu\u00e8 vol el client del jard\u00ed. Podem veure que potser vol certa planta o un tipus de gespa determinat, potser vol un jard\u00ed sec per no malgastar aigua o un jard\u00ed amb una planta que doni color tot l&#8217;any. Totes aquestes coses, que hem discutides, seran les coses a considerar per al disseny de jardins. Determinaran quin espai es crear\u00e0 i quins materials i plantes seran els m\u00e9s adequats per a la seva col\u00b7locaci\u00f3. Un cop tinguis una idea de com vols el jard\u00ed (sempre dep\u00e8n del que t&#8217;hagin dit: l&#8217;estat de l&#8217;espai, el tipus de jard\u00ed, l&#8217;\u00fas i el que vulgui el client), ser\u00e0 q\u00fcesti\u00f3 de prendre les mesures precises de l&#8217;espai disponible i fer un esb\u00f3s primer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En primer lloc, hem de saber que el paisatgisme \u00e9s una activitat professional encaminada a millorar les caracter\u00edstiques f\u00edsiques, materials i espirituals dels espais rurals o urbans, amb l&#8217;objectiu d&#8217;expressar valors est\u00e8tics i culturals. Aquest \u00e0mbit de treball inclou plantar arbres, donar forma a elements naturals i crear estructures abstractes a partir d&#8217;una varietat de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1196,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria\" \/>\n<meta property=\"og:description\" content=\"En primer lloc, hem de saber que el paisatgisme \u00e9s una activitat professional encaminada a millorar les caracter\u00edstiques f\u00edsiques, materials i espirituals dels espais rurals o urbans, amb l&#8217;objectiu d&#8217;expressar valors est\u00e8tics i culturals. Aquest \u00e0mbit de treball inclou plantar arbres, donar forma a elements naturals i crear estructures abstractes a partir d&#8217;una varietat de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00d3scar Herrera Jardineria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T20:23:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T11:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/person\\\/52ada0f10ec00d92c6731c6b0de4c904\"},\"headline\":\"En qu\u00e8 consisteix la feina del disseny de jardins\",\"datePublished\":\"2023-12-01T20:23:00+00:00\",\"dateModified\":\"2024-08-20T11:49:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/\"},\"wordCount\":451,\"publisher\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/diseno-de-jardines.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/\",\"name\":\"En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/diseno-de-jardines.jpg\",\"datePublished\":\"2023-12-01T20:23:00+00:00\",\"dateModified\":\"2024-08-20T11:49:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/diseno-de-jardines.jpg\",\"contentUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/diseno-de-jardines.jpg\",\"width\":2000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/en-que-consisteix-la-feina-del-disseny-de-jardins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En qu\u00e8 consisteix la feina del disseny de jardins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\",\"name\":\"\u00d3scar Herrera Jardineria\",\"description\":\"Dise\u00f1amos el jard\u00edn de tus sue\u00f1os\",\"publisher\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#organization\",\"name\":\"\u00d3scar Herrera Jardineria\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/oh_isologo_horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/oh_isologo_horizontal.svg\",\"width\":265,\"height\":43,\"caption\":\"\u00d3scar Herrera Jardineria\"},\"image\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ohjardineria\\\/?locale=es_ES\",\"https:\\\/\\\/www.instagram.com\\\/oscarherrera_jardines\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChQbmi2AzatSBWjc6LyAPHw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/person\\\/52ada0f10ec00d92c6731c6b0de4c904\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/desarrollo.jardineriaoscarh.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/","og_locale":"ca_ES","og_type":"article","og_title":"En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria","og_description":"En primer lloc, hem de saber que el paisatgisme \u00e9s una activitat professional encaminada a millorar les caracter\u00edstiques f\u00edsiques, materials i espirituals dels espais rurals o urbans, amb l&#8217;objectiu d&#8217;expressar valors est\u00e8tics i culturals. Aquest \u00e0mbit de treball inclou plantar arbres, donar forma a elements naturals i crear estructures abstractes a partir d&#8217;una varietat de [&hellip;]","og_url":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/","og_site_name":"\u00d3scar Herrera Jardineria","article_publisher":"https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES","article_published_time":"2023-12-01T20:23:00+00:00","article_modified_time":"2024-08-20T11:49:01+00:00","og_image":[{"width":2000,"height":1000,"url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"admin","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#article","isPartOf":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/"},"author":{"name":"admin","@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/person\/52ada0f10ec00d92c6731c6b0de4c904"},"headline":"En qu\u00e8 consisteix la feina del disseny de jardins","datePublished":"2023-12-01T20:23:00+00:00","dateModified":"2024-08-20T11:49:01+00:00","mainEntityOfPage":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/"},"wordCount":451,"publisher":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#organization"},"image":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#primaryimage"},"thumbnailUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg","articleSection":["Sin categorizar"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/","url":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/","name":"En qu\u00e8 consisteix la feina del disseny de jardins - \u00d3scar Herrera Jardineria","isPartOf":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#primaryimage"},"image":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#primaryimage"},"thumbnailUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg","datePublished":"2023-12-01T20:23:00+00:00","dateModified":"2024-08-20T11:49:01+00:00","breadcrumb":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#primaryimage","url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg","contentUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/07\/diseno-de-jardines.jpg","width":2000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/jardineriaoscarh.com\/ca\/en-que-consisteix-la-feina-del-disseny-de-jardins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jardineriaoscarh.com\/ca\/"},{"@type":"ListItem","position":2,"name":"En qu\u00e8 consisteix la feina del disseny de jardins"}]},{"@type":"WebSite","@id":"https:\/\/jardineriaoscarh.com\/ca\/#website","url":"https:\/\/jardineriaoscarh.com\/ca\/","name":"\u00d3scar Herrera Jardineria","description":"Dise\u00f1amos el jard\u00edn de tus sue\u00f1os","publisher":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jardineriaoscarh.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/jardineriaoscarh.com\/ca\/#organization","name":"\u00d3scar Herrera Jardineria","url":"https:\/\/jardineriaoscarh.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/06\/oh_isologo_horizontal.svg","contentUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/06\/oh_isologo_horizontal.svg","width":265,"height":43,"caption":"\u00d3scar Herrera Jardineria"},"image":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES","https:\/\/www.instagram.com\/oscarherrera_jardines\/","https:\/\/www.youtube.com\/channel\/UChQbmi2AzatSBWjc6LyAPHw"]},{"@type":"Person","@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/person\/52ada0f10ec00d92c6731c6b0de4c904","name":"admin","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44c520d0ee00f53bf5bce3cfe25f0f21a8b564001fa9d374716835d95b110394?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/desarrollo.jardineriaoscarh.com"]}]}},"_links":{"self":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/posts\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":0,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/posts\/1605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/media\/1196"}],"wp:attachment":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/media?parent=1605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/categories?post=1605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/tags?post=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}