{"id":2105,"date":"2025-01-15T17:20:42","date_gmt":"2025-01-15T16:20:42","guid":{"rendered":"https:\/\/jardineriaoscarh.com\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/"},"modified":"2025-01-15T19:20:08","modified_gmt":"2025-01-15T18:20:08","slug":"raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure","status":"publish","type":"portfolio_item","link":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/","title":{"rendered":"rac\u00f3 verd dissenyat per al descans i la conviv\u00e8ncia a l&#8217;aire lliure"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2099\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-1024x576.jpg\" alt=\"\" class=\"wp-image-2099\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-1024x576.jpg 1024w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-300x169.jpg 300w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-768x432.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-1536x864.jpg 1536w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2093\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-1024x576.jpg\" alt=\"\" class=\"wp-image-2093\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-1024x576.jpg 1024w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-300x169.jpg 300w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-768x432.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-1536x864.jpg 1536w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_3-Photo-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2090\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-1024x576.jpg\" alt=\"\" class=\"wp-image-2090\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-1024x576.jpg 1024w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-300x169.jpg 300w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-768x432.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-1536x864.jpg 1536w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_4-Photo-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2087\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-1024x576.jpg\" alt=\"\" class=\"wp-image-2087\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-1024x576.jpg 1024w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-300x169.jpg 300w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-768x432.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-1536x864.jpg 1536w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_5-Photo-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2096\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-1024x576.jpg\" alt=\"\" class=\"wp-image-2096\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-1024x576.jpg 1024w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-300x169.jpg 300w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-768x432.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-1536x864.jpg 1536w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_1-Photo-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"1024\" src=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1-476x1024.jpg\" alt=\"\" class=\"wp-image-2102\" srcset=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1-476x1024.jpg 476w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1-140x300.jpg 140w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1-768x1650.jpg 768w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1-715x1536.jpg 715w, https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_6-Photo-1.jpg 926w\" sizes=\"(max-width: 476px) 100vw, 476px\" \/><\/figure>\n","protected":false},"featured_media":2100,"template":"","class_list":["post-2105","portfolio_item","type-portfolio_item","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans<\/title>\n<meta name=\"description\" content=\"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l&#039;aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans\" \/>\n<meta property=\"og:description\" content=\"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l&#039;aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00d3scar Herrera Jardineria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T18:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/\",\"name\":\"Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/D4_2-Photo-scaled.jpg\",\"datePublished\":\"2025-01-15T16:20:42+00:00\",\"dateModified\":\"2025-01-15T18:20:08+00:00\",\"description\":\"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l'aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/D4_2-Photo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/D4_2-Photo-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/portfolio_item\\\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"rac\u00f3 verd dissenyat per al descans i la conviv\u00e8ncia a l&#8217;aire lliure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\",\"name\":\"\u00d3scar Herrera Jardineria\",\"description\":\"Dise\u00f1amos el jard\u00edn de tus sue\u00f1os\",\"publisher\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#organization\",\"name\":\"\u00d3scar Herrera Jardineria\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/oh_isologo_horizontal.svg\",\"contentUrl\":\"https:\\\/\\\/jardineriaoscarh.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/oh_isologo_horizontal.svg\",\"width\":265,\"height\":43,\"caption\":\"\u00d3scar Herrera Jardineria\"},\"image\":{\"@id\":\"https:\\\/\\\/jardineriaoscarh.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ohjardineria\\\/?locale=es_ES\",\"https:\\\/\\\/www.instagram.com\\\/oscarherrera_jardines\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChQbmi2AzatSBWjc6LyAPHw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans","description":"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l'aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/","og_locale":"ca_ES","og_type":"article","og_title":"Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans","og_description":"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l'aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.","og_url":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/","og_site_name":"\u00d3scar Herrera Jardineria","article_publisher":"https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES","article_modified_time":"2025-01-15T18:20:08+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/","url":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/","name":"Parc Urb\u00e0: Un Rac\u00f3 Verd per al Descans","isPartOf":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/#primaryimage"},"image":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/#primaryimage"},"thumbnailUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-scaled.jpg","datePublished":"2025-01-15T16:20:42+00:00","dateModified":"2025-01-15T18:20:08+00:00","description":"Descobreix un rac\u00f3 verd a la ciutat, dissenyat per al descans a l'aire lliure. Un espai acollidor amb vegetaci\u00f3 i zones de relax.","breadcrumb":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/#primaryimage","url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-scaled.jpg","contentUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2025\/01\/D4_2-Photo-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/jardineriaoscarh.com\/ca\/portfolio_item\/raco-verd-dissenyat-per-al-descans-i-la-convivencia-a-laire-lliure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jardineriaoscarh.com\/ca\/"},{"@type":"ListItem","position":2,"name":"rac\u00f3 verd dissenyat per al descans i la conviv\u00e8ncia a l&#8217;aire lliure"}]},{"@type":"WebSite","@id":"https:\/\/jardineriaoscarh.com\/ca\/#website","url":"https:\/\/jardineriaoscarh.com\/ca\/","name":"\u00d3scar Herrera Jardineria","description":"Dise\u00f1amos el jard\u00edn de tus sue\u00f1os","publisher":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jardineriaoscarh.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/jardineriaoscarh.com\/ca\/#organization","name":"\u00d3scar Herrera Jardineria","url":"https:\/\/jardineriaoscarh.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/06\/oh_isologo_horizontal.svg","contentUrl":"https:\/\/jardineriaoscarh.com\/wp-content\/uploads\/2024\/06\/oh_isologo_horizontal.svg","width":265,"height":43,"caption":"\u00d3scar Herrera Jardineria"},"image":{"@id":"https:\/\/jardineriaoscarh.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ohjardineria\/?locale=es_ES","https:\/\/www.instagram.com\/oscarherrera_jardines\/","https:\/\/www.youtube.com\/channel\/UChQbmi2AzatSBWjc6LyAPHw"]}]}},"_links":{"self":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/portfolio_item\/2105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/portfolio_item"}],"about":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/types\/portfolio_item"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/media\/2100"}],"wp:attachment":[{"href":"https:\/\/jardineriaoscarh.com\/ca\/wp-json\/wp\/v2\/media?parent=2105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}